{"id":302,"date":"2012-12-10T10:33:58","date_gmt":"2012-12-10T09:33:58","guid":{"rendered":"http:\/\/www.spm-prod.fr\/site\/?p=302"},"modified":"2013-05-31T10:33:05","modified_gmt":"2013-05-31T09:33:05","slug":"11022013-korpiklaani-metsatoll","status":"publish","type":"post","link":"http:\/\/www.spm-prod.fr\/site\/2012\/12\/10\/11022013-korpiklaani-metsatoll\/","title":{"rendered":"[11\/02\/2013] KORPIKLAANI + METSATOLL"},"content":{"rendered":"<p><a href=\"http:\/\/www.spm-prod.fr\/site\/wp-content\/uploads\/2012\/12\/Korpiklaani2013.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-303\" title=\"Korpiklaani2013\" alt=\"\" src=\"http:\/\/www.spm-prod.fr\/site\/wp-content\/uploads\/2012\/12\/Korpiklaani2013-726x1024.jpg\" width=\"620\" height=\"874\" srcset=\"http:\/\/www.spm-prod.fr\/site\/wp-content\/uploads\/2012\/12\/Korpiklaani2013-726x1024.jpg 726w, http:\/\/www.spm-prod.fr\/site\/wp-content\/uploads\/2012\/12\/Korpiklaani2013-212x300.jpg 212w, http:\/\/www.spm-prod.fr\/site\/wp-content\/uploads\/2012\/12\/Korpiklaani2013.jpg 1258w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Toulouse &#8211; Le Bikini<\/p>\n","protected":false},"author":1,"featured_media":304,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[31,68],"class_list":["post-302","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-concerts","tag-korpiklaani","tag-metsatoll"],"_links":{"self":[{"href":"http:\/\/www.spm-prod.fr\/site\/wp-json\/wp\/v2\/posts\/302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.spm-prod.fr\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.spm-prod.fr\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.spm-prod.fr\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.spm-prod.fr\/site\/wp-json\/wp\/v2\/comments?post=302"}],"version-history":[{"count":4,"href":"http:\/\/www.spm-prod.fr\/site\/wp-json\/wp\/v2\/posts\/302\/revisions"}],"predecessor-version":[{"id":619,"href":"http:\/\/www.spm-prod.fr\/site\/wp-json\/wp\/v2\/posts\/302\/revisions\/619"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.spm-prod.fr\/site\/wp-json\/wp\/v2\/media\/304"}],"wp:attachment":[{"href":"http:\/\/www.spm-prod.fr\/site\/wp-json\/wp\/v2\/media?parent=302"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.spm-prod.fr\/site\/wp-json\/wp\/v2\/categories?post=302"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.spm-prod.fr\/site\/wp-json\/wp\/v2\/tags?post=302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}